{"id":17,"count":29,"description":"","link":"https:\/\/foodsafety4africa.eu\/de\/category\/project-news\/","name":"Pressemitteilungen","slug":"project-news","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/foodsafety4africa.eu\/de\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foodsafety4africa.eu\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/foodsafety4africa.eu\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/foodsafety4africa.eu\/de\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}